{"id":2026138,"date":"2025-03-06T18:50:30","date_gmt":"2025-03-06T17:50:30","guid":{"rendered":"https:\/\/thingstodoinamsterdam.com\/?p=2026138"},"modified":"2026-04-28T16:29:13","modified_gmt":"2026-04-28T14:29:13","slug":"tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam","status":"publish","type":"post","link":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/","title":{"rendered":"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][buttonsticky title=&#8221;Ach\u00e8te des truffes magiques en ligne sur microdosebros.com&#8221; link=&#8221;https:\/\/www.microdosebros.com\/product-category\/shroomshop\/best-shroomshop\/?ref=49&#8243; target=&#8221;true&#8221; nofollow=&#8221;true&#8221; el_id=&#8221;1731674534043-cb59c1e9-ec20&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>Depuis l&#8217;interdiction des champignons magiques plus puissants en 2008, les truffes magiques sont vendues comme substituts l\u00e9gaux par les <a href=\"https:\/\/thingstodoinamsterdam.com\/fr\/smartshops-amsterdam\/\">smartshops d&#8217;Amsterdam<\/a>. Les truffes contiennent la m\u00eame substance active : la psilocybine. Elles modifient l&#8217;exp\u00e9rience de la r\u00e9alit\u00e9, de l&#8217;espace et du temps. Ton environnement, tes sentiments et tes perceptions sont \u00e9galement v\u00e9cus diff\u00e9remment. La puissance varie selon l&#8217;esp\u00e8ce et la truffe. C&#8217;est un produit naturel, donc une truffe peut contenir plus de substances actives que d&#8217;autres de la m\u00eame esp\u00e8ce. Les truffes magiques peuvent \u00eatre utilis\u00e9es de mani\u00e8re r\u00e9cr\u00e9ative ou pour obtenir des perspectives psychologiques, spirituelles ou philosophiques plus profondes.      <\/strong>[\/vc_column_text][vc_column_text]Alors, que sont r\u00e9ellement les truffes ? Que sont les truffes magiques ? O\u00f9 peux-tu les acheter \u00e0 Amsterdam ? Quels sont les prix des truffes \u00e0 Amsterdam et o\u00f9 peux-tu les acheter dans la ville ?   <\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#que-sont-les-truffes-magiques\" >Que sont les truffes magiques ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#ou-puis-je-acheter-des-truffes-a-amsterdam\" >O\u00f9 puis-je acheter des truffes \u00e0 Amsterdam ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#quel-est-le-bon-dosage-pour-les-truffes-magiques\" >Quel est le bon dosage pour les truffes magiques ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#quels-sont-les-risques-lies-a-lutilisation-de-truffes\" >Quels sont les risques li\u00e9s \u00e0 l&#8217;utilisation de truffes ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#conseils-utiles-pour-lutilisation-de-truffes\" >Conseils utiles pour l&#8217;utilisation de truffes<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Commen\u00e7ons par les bases. Qu&#8217;est-ce qu&#8217;une truffe magique, au juste ? Les truffes sont des scl\u00e9rotes, des masses de racines souterraines de champignons magiques appel\u00e9es myc\u00e9lium. Elles servent de r\u00e9serves alimentaires pour les champignons magiques qui poussent au-dessus du sol. Les truffes contiennent \u00e9galement les substances chimiques hallucinog\u00e8nes psilocybine et psilocine. Lorsqu&#8217;elles sont ing\u00e9r\u00e9es, les truffes peuvent \u00ab d\u00e9clencher \u00bb un trip hallucinog\u00e8ne qui peut durer jusqu&#8217;\u00e0 6 heures. L&#8217;intensit\u00e9 du trip d\u00e9pend de nombreux facteurs, notamment la dose, la puissance des truffes et la sensibilit\u00e9 de l&#8217;utilisateur \u00e0 la psilocybine.      <\/p>\n<p>Dans cet article, nous nous concentrerons cependant sur les \u00ab truffes magiques \u00bb psychoactives qui sont vendues l\u00e9galement dans les smartshops d&#8217;Amsterdam pour un usage r\u00e9cr\u00e9atif.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<p style=\"text-align: center;\">Tu es \u00e0 Amsterdam et tu cherches un smartshop de confiance ? Visite <a href=\"https:\/\/thingstodoinamsterdam.com\/fr\/smartshops-amsterdam\/the-magic-mushroom-gallery\/\">The Magic Mushroom Gallery<\/a> <\/p>\n<p style=\"text-align: center;\">Tu n&#8217;es pas \u00e0 Amsterdam, mais tu es int\u00e9ress\u00e9 par les truffes magiques ?<\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 style=\"text-align: center;\">Commander des truffes magiques d&#8217;Amsterdam en ligne<\/h3>\n<p style=\"text-align: center;\">Certains smartshops d&#8217;Amsterdam ont commenc\u00e9 \u00e0 vendre leurs produits en ligne et \u00e0 exp\u00e9dier dans toute l&#8217;Europe. Par cons\u00e9quent, tu peux maintenant vivre une exp\u00e9rience psych\u00e9d\u00e9lique en toute s\u00e9curit\u00e9 dans ton propre pays. Nous avons \u00e9tabli des liens avec des vendeurs de qualit\u00e9 que tu peux utiliser pour commander des truffes magiques en ligne :  <\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">1 &#8211; <strong><a href=\"https:\/\/www.microdosebros.com\/product-category\/shroomshop\/best-shroomshop\/?ref=49\" target=\"_blank\" rel=\"noopener nofollow\">Microdosebros<\/a><\/strong> : Nous avons travaill\u00e9 avec ce vendeur et l&#8217;avons utilis\u00e9 pendant longtemps. Excellente qualit\u00e9 et excellent service ! Lou\u00e9 par les clients dans d&#8217;innombrables avis Google. Commande avec notre <strong>code de r\u00e9duction exclusif<\/strong> <em>Amsterdam10<\/em> et obtiens 10 % de r\u00e9duction.   <\/p>\n<p style=\"text-align: center;\">2 &#8211;<span style=\"box-sizing: border-box; margin: 0; padding: 0; text-align: left;\"><strong> <a href=\"https:\/\/jdt8.net\/c\/?si=17221&amp;li=1743938&amp;wi=331407&amp;ws=EN&amp;dl=shroomshop\/magic-truffles\/\" target=\"_blank\" rel=\"noopener\">Tatanka<\/a><\/strong> : L&#8217;un des smartshops les plus anciens et les plus populaires<\/span> d&#8217;Amsterdam. Connu pour sa qualit\u00e9 et ses employ\u00e9s comp\u00e9tents. Prix en ligne comp\u00e9titifs !  <\/p>\n<p style=\"text-align: center;\">3 &#8211; <strong><a href=\"https:\/\/jdt8.net\/c\/?si=17220&amp;li=1743937&amp;wi=331407&amp;ws=EN&amp;dl=shroomshop\/magic-truffles\/\" target=\"_blank\" rel=\"noopener\">Headshop<\/a><\/strong> : Un autre acteur bien connu dans notre capitale qui existe depuis 1968. Livrant maintenant aussi des psych\u00e9d\u00e9liques naturels \u00e0 domicile dans toute l&#8217;Europe. <\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;2535835&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"que-sont-les-truffes-magiques\"><\/span>Que sont les truffes magiques ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les truffes magiques sont l&#8217;un des types de psych\u00e9d\u00e9liques les plus extraordinaires au monde. Ces scl\u00e9rotes ne sont pas techniquement des champignons, mais ils font partie du m\u00eame organisme. Si tu te demandes quelle est la diff\u00e9rence entre ces truffes et les champignons, tu n&#8217;es pas seul. Bien que les deux contiennent la substance psych\u00e9d\u00e9lique psilocybine, ce sont deux produits diff\u00e9rents.   <\/p>\n<p>C&#8217;est parce que les truffes poussent sous terre, tandis que les champignons poussent au-dessus du sol. Il est \u00e9galement bon de savoir que les truffes magiques ne sont pas vraiment des \u00ab truffes \u00bb mais des \u00ab scl\u00e9rotes \u00bb. Les scl\u00e9rotes sont des champignons qui poussent \u00e0 partir du m\u00eame organisme que les champignons psych\u00e9d\u00e9liques \u2014 mais ne sont donc pas des champignons eux-m\u00eames.  <\/p>\n<p>Depuis l\u2019interdiction des champignons, les truffes sont vendues comme substituts. Les truffes sont l\u00e9gales. Les substances actives dans les champignons et les truffes sont interdites. Les truffes contiennent des substances qui alt\u00e8rent le fonctionnement du cerveau. Les substances actives comprennent la psilocine et la psilocybine.    <\/p>\n<p>Les truffes contiennent les m\u00eames substances actives. Elles modifient l\u2019exp\u00e9rience de la r\u00e9alit\u00e9, de l\u2019espace et du temps. Ton environnement, tes sentiments et ta perception sont \u00e9galement v\u00e9cus diff\u00e9remment. La puissance varie selon l\u2019esp\u00e8ce et la truffe. C\u2019est un produit naturel, donc une truffe peut contenir plus de substances actives que d\u2019autres de la m\u00eame esp\u00e8ce.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"ou-puis-je-acheter-des-truffes-a-amsterdam\"><\/span>O\u00f9 puis-je acheter des truffes \u00e0 Amsterdam ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le meilleur et le plus s\u00fbr endroit pour acheter des truffes \u00e0 Amsterdam est dans un smartshop sp\u00e9cialis\u00e9. Nous insistons pour que toute personne pr\u00e9voyant d&#8217;utiliser des truffes soit bien inform\u00e9e et bien pr\u00e9par\u00e9e. Il est donc sage de choisir un smartshop avec des employ\u00e9s comp\u00e9tents qui prennent le temps de bien informer leurs clients. Voici quelques boutiques recommand\u00e9es o\u00f9 tu peux acheter tes truffes \u00e0 Amsterdam :   <\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li><strong>The Magic Mushroom Gallery : <\/strong>l&#8217;un des plus anciens smartshops de la ville. Chez <a href=\"https:\/\/thingstodoinamsterdam.com\/fr\/smartshops-amsterdam\/the-magic-mushroom-gallery\/\">The Magic Mushroom Gallery<\/a>, les employ\u00e9s sont exp\u00e9riment\u00e9s et comp\u00e9tents, ils ont de nombreuses vari\u00e9t\u00e9s de truffes magiques et seront heureux de t&#8217;aider \u00e0 choisir la bonne. Ils ont deux magasins dans le centre-ville, un au march\u00e9 aux fleurs et un dans la Spuitstraat.  <\/li>\n<li><strong>Azarius :<\/strong> Azarius a un smartshop en ligne et physique. Le magasin physique est situ\u00e9 dans la Kerkstraat \u00e0 Amsterdam. La boutique se trouve \u00e0 2 minutes \u00e0 pied du <a href=\"https:\/\/thingstodoinamsterdam.com\/places-sightseeing-amsterdam\/leidseplein\/\">Leidseplein<\/a>.  <\/li>\n<li><strong>Kokopelli :<\/strong> Cette boutique est proche du <a href=\"https:\/\/thingstodoinamsterdam.com\/fr\/le-quartier-rouge\/\">quartier rouge<\/a> dans la Warmoestraat. Elle est assez curieuse et belle. Elle se trouve \u00e0 seulement 7 minutes \u00e0 pied de la <a href=\"https:\/\/thingstodoinamsterdam.com\/fr\/transports-a-amsterdam\/amsterdam-central-station\/\">gare centrale d&#8217;Amsterdam<\/a> et vaut vraiment le d\u00e9tour m\u00eame si tu n&#8217;es pas int\u00e9ress\u00e9 par les truffes.  <\/li>\n<li><strong>Tatanka :<\/strong> Un grand smartshop spacieux situ\u00e9 sur le Leidseplein.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h4 style=\"text-align: left;\">Tu n&#8217;es pas \u00e0 Amsterdam, mais tu es int\u00e9ress\u00e9 par les truffes magiques ? Tu peux aussi les commander en ligne ! <\/h4>\n<p>Si tu as trouv\u00e9 cet article et que tu es int\u00e9ress\u00e9 par les truffes magiques, mais que tu ne pr\u00e9vois pas de visiter Amsterdam prochainement, tu peux les acheter en ligne \u00e0 la place.<a href=\"https:\/\/www.microdosebros.com\/?ref=49&amp;campaign=home\" target=\"_blank\" rel=\"noopener nofollow\"> Microdosebros.com<\/a> est une boutique en ligne sp\u00e9cialis\u00e9e dans la vente (en ligne) de truffes magiques et les exp\u00e9die \u00e0 l\u2019international. Ils fournissent \u00e9galement des informations sur comment <a href=\"https:\/\/www.microdosebros.com\/microdosing-magic-truffles-the-ultimate-guide-to-microdosing\/?ref=49&amp;campaign=microdose\" target=\"_blank\" rel=\"noopener, nofollow noopener\">microdoser les truffes<\/a> ; la pratique consistant \u00e0 prendre de tr\u00e8s petites quantit\u00e9s de psilocybine afin de tester ou de b\u00e9n\u00e9ficier de son action physiologique tout en minimisant les effets secondaires ind\u00e9sirables.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 style=\"text-align: center;\">Commander des truffes magiques d&#8217;Amsterdam en ligne<\/h3>\n<p style=\"text-align: center;\">Certaines smartshops d\u2019Amsterdam ont commenc\u00e9 \u00e0 vendre leurs produits en ligne et \u00e0 les exp\u00e9dier \u00e0 l\u2019international. Nous avons s\u00e9lectionn\u00e9 quelques vendeurs de qualit\u00e9 que tu peux utiliser pour commander des truffes magiques en ligne : <\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">1 &#8211; <strong><a href=\"https:\/\/www.microdosebros.com\/product-category\/shroomshop\/best-shroomshop\/?ref=49\" target=\"_blank\" rel=\"noopener nofollow\">Microdosebros<\/a><\/strong> : Nous avons travaill\u00e9 avec ce vendeur et l&#8217;avons utilis\u00e9 pendant longtemps. Excellente qualit\u00e9 et excellent service ! Lou\u00e9 par les clients dans d&#8217;innombrables avis Google. Commande avec notre <strong>code de r\u00e9duction exclusif<\/strong> <em>Amsterdam10<\/em> et obtiens 10 % de r\u00e9duction.   <\/p>\n<p style=\"text-align: center;\">2 &#8211;<span style=\"box-sizing: border-box; margin: 0; padding: 0; text-align: left;\"><strong> <a href=\"https:\/\/jdt8.net\/c\/?si=17221&amp;li=1743938&amp;wi=331407&amp;ws=EN&amp;dl=shroomshop\/magic-truffles\/\" target=\"_blank\" rel=\"noopener\">Tatanka<\/a><\/strong> : L&#8217;un des smartshops les plus anciens et les plus populaires<\/span> d&#8217;Amsterdam. Connu pour sa qualit\u00e9 et ses employ\u00e9s comp\u00e9tents. Prix en ligne comp\u00e9titifs !  <\/p>\n<p style=\"text-align: center;\">3 &#8211; <strong><a href=\"https:\/\/jdt8.net\/c\/?si=17220&amp;li=1743937&amp;wi=331407&amp;ws=EN&amp;dl=shroomshop\/magic-truffles\/\" target=\"_blank\" rel=\"noopener\">Headshop<\/a><\/strong> : Un autre acteur bien connu dans notre capitale qui existe depuis 1968. Livrant maintenant aussi des psych\u00e9d\u00e9liques naturels \u00e0 domicile dans toute l&#8217;Europe. <\/p>\n<p>[\/vc_column_text][button title=&#8221;Ach\u00e8te des truffes magiques en ligne sur microdosebros.com&#8221; link=&#8221;https:\/\/www.microdosebros.com\/product-category\/shroomshop\/best-shroomshop\/?ref=49&#8243; icon=&#8221;&#8221; button_align=&#8221;center&#8221; target=&#8221;true&#8221; nofollow=&#8221;true&#8221; el_id=&#8221;1650193038339-1b893c6d-cb99&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">&#8211; Commande avec notre <strong>code de r\u00e9duction exclusif<\/strong> <em>Amsterdam10<\/em> et obtiens 10 % de r\u00e9duction &#8211;<\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"quel-est-le-bon-dosage-pour-les-truffes-magiques\"><\/span>Quel est le bon dosage pour les truffes magiques ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>C&#8217;est une question parfaite \u00e0 poser lors de l&#8217;achat de truffes. Un bon smartshop conna\u00eet bien les diff\u00e9rentes vari\u00e9t\u00e9s qu&#8217;il vend et peut te fournir des conseils pr\u00e9cis. Si tu sens que le vendeur ne conna\u00eet pas son produit, nous te recommandons de trouver un autre smartshop. Les utilisateurs d\u00e9butants doivent toujours commencer avec un dosage l\u00e9ger, afin de pouvoir explorer comment la psilocybine les affecte. Les \u00e9l\u00e9ments \u00e0 prendre en compte pour ton dosage sont :    <\/p>\n<ul>\n<li>Puissance de la vari\u00e9t\u00e9 sp\u00e9cifique de truffes que tu as achet\u00e9e<\/li>\n<li>Poids corporel<\/li>\n<li>Sensibilit\u00e9 aux hallucinog\u00e8nes<\/li>\n<\/ul>\n<p>Ces trois facteurs peuvent varier consid\u00e9rablement d&#8217;une situation \u00e0 l&#8217;autre ; par cons\u00e9quent, le dosage correct varie \u00e9galement en cons\u00e9quence. Notre partenaire<span style=\"box-sizing: border-box; margin: 0px; padding: 0px;\">, <a href=\"https:\/\/www.microdosebros.com\/magic-mushroom-magic-truffles-dosage-calculator\/?campaign=dosage&amp;ref=49\" target=\"_blank\" rel=\"noopener\">Microdosebros, a d\u00e9velopp\u00e9 un calculateur de dosage<\/a> pour aider \u00e0 estimer <\/span>le dosage correct. Cependant, ces indications sont uniquement \u00e0 titre indicatif, car elles ne tiennent pas compte de la puissance des truffes ni de la sensibilit\u00e9 aux hallucinog\u00e8nes. Pour un poids corporel de 80 kg, une dose normale est d&#8217;environ 10 grammes de truffes fra\u00eeches.   <\/p>\n<h3>Tableau de dosage<\/h3>\n<table style=\"width: 100%;\">\n<thead>\n<tr>\n<th>Poids corporel<\/th>\n<th>Dosage l\u00e9ger<\/th>\n<th>Dosage moyen<\/th>\n<th>Dosage fort<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: center;\"> 60 kg<\/td>\n<td style=\"text-align: center;\">5,6 grammes<\/td>\n<td style=\"text-align: center;\">7,8 grammes<\/td>\n<td style=\"text-align: center;\">13,2 grammes<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">80 kg<\/td>\n<td style=\"text-align: center;\">7,5 grammes<\/td>\n<td style=\"text-align: center;\">10,4 grammes<\/td>\n<td style=\"text-align: center;\">17,6 grammes<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">100 kg<\/td>\n<td style=\"text-align: center;\">9,4 grammes<\/td>\n<td style=\"text-align: center;\">13,0 grammes<\/td>\n<td style=\"text-align: center;\">22,0 grammes<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">120 kg<\/td>\n<td style=\"text-align: center;\">11,3 grammes<\/td>\n<td style=\"text-align: center;\">15,6 grammes<\/td>\n<td style=\"text-align: center;\">26,4 grammes<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>* <em>Ces dosages sont uniquement \u00e0 titre indicatif et bas\u00e9s sur des truffes magiques fra\u00eeches de puissance moyenne.<\/em><\/p>\n<h3>Diff\u00e9rentes vari\u00e9t\u00e9s et puissance<\/h3>\n<p>Assure-toi toujours de t&#8217;informer au smartshop sur les diff\u00e9rentes vari\u00e9t\u00e9s de truffes magiques et leur puissance. Ils devraient conna\u00eetre leurs produits au mieux. Cela dit, voici quelques-unes des vari\u00e9t\u00e9s les plus populaires, ainsi que leur puissance.  <\/p>\n<h4>Truffes magiques pour d\u00e9butants<\/h4>\n<ul>\n<li>Tampanensis<\/li>\n<li>Fantasia<\/li>\n<li>Atlantis<\/li>\n<li>Mexicana<\/li>\n<\/ul>\n<h4>Truffes magiques moyennes<\/h4>\n<ul>\n<li>Pink paradise<\/li>\n<li>Hollandia<\/li>\n<li>Sex on the beach<\/li>\n<li>Double vision<\/li>\n<\/ul>\n<h4>Truffes magiques les plus fortes<\/h4>\n<ul>\n<li>High Hawaiians<\/li>\n<li>Royal Dutch<\/li>\n<li>Nirvana<\/li>\n<li>Sonic shrooms<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3>Combien co\u00fbtent les truffes magiques ?<\/h3>\n<p>Les truffes magiques sont g\u00e9n\u00e9ralement vendues en paquets de 15 grammes, ce qui devrait \u00eatre suffisant pour la plupart des utilisateurs. Elles devraient co\u00fbter entre 20 \u20ac et 35 \u20ac par paquet. Les prix peuvent varier selon le magasin, la vari\u00e9t\u00e9 et le poids.  <\/p>\n<h3>Les truffes (magiques) sont-elles l\u00e9gales aux Pays-Bas ?<\/h3>\n<p>Oui, les truffes (magiques) sont l\u00e9gales aux Pays-Bas. Les scl\u00e9rotes sont form\u00e9s par des champignons souterrains qui stockent des nutriments et les prot\u00e8gent contre le froid, la s\u00e9cheresse et la chaleur naturelle. Ils contiennent de la psilocybine, qui donne un \u00e9tat de conscience color\u00e9 qui dure environ 4 \u00e0 6 heures.  <\/p>\n<p>Les truffes magiques sont officiellement un \u00ab sous-produit \u00bb des champignons magiques et ne contiennent aucune substance nocive d\u00e9tectable. Les truffes magiques peuvent \u00eatre vendues aux Pays-Bas, mais pas les champignons magiques car ils sont ill\u00e9gaux. Tu peux acheter diff\u00e9rents types de truffes magiques dans les smartshops, o\u00f9 elles sont vendues l\u00e9galement. Seules les truffes fra\u00eeches sont autoris\u00e9es \u00e0 la vente ; les truffes s\u00e9ch\u00e9es sont interdites.   <\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9808 size-full\" src=\"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/magic-truffles-in-Amsterdam.jpg\" alt=\"truffes magiques \u00e0 Amsterdam\" width=\"900\" height=\"552\" srcset=\"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/magic-truffles-in-Amsterdam.jpg 900w, https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/magic-truffles-in-Amsterdam-300x184.jpg 300w, https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/magic-truffles-in-Amsterdam-768x471.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<h3>Comment utilise-t-on les truffes ?<\/h3>\n<p>Les truffes peuvent \u00eatre utilis\u00e9es de diff\u00e9rentes mani\u00e8res. La plupart des gens les mangent simplement. Tu peux aussi en faire du th\u00e9 ou les utiliser comme ingr\u00e9dient dans un plat. Par exemple, il existe aussi des barres de chocolat avec des truffes incorpor\u00e9es et la plupart des gens aiment les ajouter \u00e0 leurs p\u00e2tes. Tu commences g\u00e9n\u00e9ralement \u00e0 ressentir l&#8217;effet une demi-heure apr\u00e8s avoir mang\u00e9 ton plat.    <\/p>\n<p>Si tu as l&#8217;estomac plein, il peut falloir plus de temps avant de ressentir les effets des truffes. Si tu les ajoutes \u00e0 ton th\u00e9, tu peux le remarquer un peu plus t\u00f4t ; l&#8217;effet est donc plus prononc\u00e9. Les mettre dans ton chocolat peut \u00e9galement produire un effet plus intense. La dur\u00e9e de l&#8217;effet varie g\u00e9n\u00e9ralement de 3 \u00e0 8 heures.   <\/p>\n<h3>Comment fonctionnent les truffes ?<\/h3>\n<p>Les truffes font partie du groupe des substances alt\u00e9rant la conscience et hallucinog\u00e8nes. Les effets varient et d\u00e9pendent, entre autres, de ta sensibilit\u00e9 personnelle, de ton humeur et de la dose. Les substances actives psilocine et psilocybine sont tr\u00e8s similaires \u00e0 la s\u00e9rotonine propre au corps (le neurotransmetteur).  <\/p>\n<p>Voici quelques effets des truffes sur le cerveau :<\/p>\n<p>Les effets et l&#8217;intensit\u00e9 de l&#8217;effet d\u00e9pendent de ta dose et de ta sensibilit\u00e9 personnelle. Tu ressens l&#8217;effet par vagues. Un moment peut \u00eatre plus intense qu&#8217;un autre.  <\/p>\n<p><strong>Effets positifs :<\/strong><\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Renforcement des sentiments et des sens agr\u00e9ables<\/li>\n<li>Rire (fou rire)<\/li>\n<li>La musique sonne diff\u00e9remment, plus profonde, plus immersive<\/li>\n<li>Les couleurs deviennent plus intenses<\/li>\n<li>Une sensation d\u00e9tendue, joyeuse, \u00e9nergique, \u00ab planante \u00bb<\/li>\n<li>Ressentir des \u00e9motions dont tu n&#8217;es normalement pas conscient<\/li>\n<li>Hallucinations visuelles<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p><strong>Effets n\u00e9gatifs :<\/strong><\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Agitation, sentiment de confusion<\/li>\n<li>Naus\u00e9e<\/li>\n<li>Mal de t\u00eate<\/li>\n<li>Soif, bouche s\u00e8che<\/li>\n<li>Sensation de chaud ou de froid<\/li>\n<li>Troubles gastriques et intestinaux<\/li>\n<li>Renforcement des sentiments d\u00e9sagr\u00e9ables<\/li>\n<li>Moins de contr\u00f4le sur les \u00e9motions et le comportement<\/li>\n<li>Trip anxieux et sentiments intenses et douloureux<\/li>\n<li>Peur que les effets ne passent plus<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>Diff\u00e9rents types d&#8217;effets caract\u00e9risent les truffes. Tu peux ressentir les effets par vagues et\/ou \u00ab boucles \u00bb. L&#8217;intensit\u00e9 vient aussi par vagues et finit par diminuer. Parfois, les truffes magiques donnent une sensation \u00ab agr\u00e9able \u00bb, tu souris, tu es joyeux et le monde semble beau et color\u00e9. La musique est intense lorsque tu l&#8217;\u00e9coutes.    <\/p>\n<p>Parfois, tu as un flux de pens\u00e9es fou, tu ne comprends pas grand-chose \u00e0 ce qui se passe autour de toi ou m\u00eame \u00e0 tes propres pens\u00e9es. Parfois, il est difficile pour toi de former des mots. Tu peux aussi avoir de fortes hallucinations visuelles. Cela n&#8217;arrive pas toujours et d\u00e9pend fortement de ta sensibilit\u00e9 personnelle, de la dose et du type de truffe.   <\/p>\n<p>Tu ne peux pas pr\u00e9dire exactement quels effets tu obtiendras lorsque tu utilises des truffes. Les gens vivent les truffes tr\u00e8s diff\u00e9remment. Certains peuvent trouver les effets assez intenses, et d&#8217;autres non.  <\/p>\n<p>Les truffes ne sont g\u00e9n\u00e9ralement pas consid\u00e9r\u00e9es comme un risque pour la sant\u00e9. Les substances actives ne sont pas nocives. Cependant, les gens peuvent avoir des probl\u00e8mes en raison d&#8217;une utilisation irresponsable. Les sympt\u00f4mes n\u00e9gatifs peuvent principalement survenir dans le mauvais environnement, en raison de la sensibilit\u00e9 individuelle, d&#8217;un dosage \u00e9lev\u00e9, etc.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<p style=\"text-align: center;\">Tu es \u00e0 Amsterdam et tu cherches un smartshop de confiance ? Visite <a href=\"https:\/\/thingstodoinamsterdam.com\/fr\/smartshops-amsterdam\/the-magic-mushroom-gallery\/\">The Magic Mushroom Gallery<\/a> <\/p>\n<p style=\"text-align: center;\">Tu n&#8217;es pas \u00e0 Amsterdam, mais tu es int\u00e9ress\u00e9 par les truffes magiques ?<\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 style=\"text-align: center;\">Commander des truffes magiques d&#8217;Amsterdam en ligne<\/h3>\n<p style=\"text-align: center;\">Certaines smartshops d\u2019Amsterdam ont commenc\u00e9 \u00e0 vendre leurs produits en ligne et \u00e0 les exp\u00e9dier \u00e0 l\u2019international. Nous avons s\u00e9lectionn\u00e9 quelques vendeurs de qualit\u00e9 que tu peux utiliser pour commander des truffes magiques en ligne : <\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">1 &#8211; <strong><a href=\"https:\/\/www.microdosebros.com\/product-category\/shroomshop\/best-shroomshop\/?ref=49\" target=\"_blank\" rel=\"noopener nofollow\">Microdosebros<\/a><\/strong> : Nous avons travaill\u00e9 avec ce vendeur et l&#8217;avons utilis\u00e9 pendant longtemps. Excellente qualit\u00e9 et excellent service ! Lou\u00e9 par les clients dans d&#8217;innombrables avis Google. Commande avec notre <strong>code de r\u00e9duction exclusif<\/strong> <em>Amsterdam10<\/em> et obtiens 10 % de r\u00e9duction.   <\/p>\n<p style=\"text-align: center;\">2 &#8211;<span style=\"box-sizing: border-box; margin: 0; padding: 0; text-align: left;\"><strong> <a href=\"https:\/\/jdt8.net\/c\/?si=17221&amp;li=1743938&amp;wi=331407&amp;ws=EN&amp;dl=shroomshop\/magic-truffles\/\" target=\"_blank\" rel=\"noopener\">Tatanka<\/a><\/strong> : L&#8217;un des smartshops les plus anciens et les plus populaires<\/span> d&#8217;Amsterdam. Connu pour sa qualit\u00e9 et ses employ\u00e9s comp\u00e9tents. Prix en ligne comp\u00e9titifs !  <\/p>\n<p style=\"text-align: center;\">3 &#8211; <strong><a href=\"https:\/\/jdt8.net\/c\/?si=17220&amp;li=1743937&amp;wi=331407&amp;ws=EN&amp;dl=shroomshop\/magic-truffles\/\" target=\"_blank\" rel=\"noopener\">Headshop<\/a><\/strong> : Un autre acteur bien connu dans notre capitale qui existe depuis 1968. Livrant maintenant aussi des psych\u00e9d\u00e9liques naturels \u00e0 domicile dans toute l&#8217;Europe. <\/p>\n<p>[\/vc_column_text][button title=&#8221;Ach\u00e8te des truffes magiques en ligne sur microdosebros.com&#8221; link=&#8221;https:\/\/www.microdosebros.com\/product-category\/shroomshop\/best-shroomshop\/?ref=49&#8243; icon=&#8221;&#8221; button_align=&#8221;center&#8221; target=&#8221;true&#8221; nofollow=&#8221;true&#8221; el_id=&#8221;1650193494773-c31a2190-3d49&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"quels-sont-les-risques-lies-a-lutilisation-de-truffes\"><\/span>Quels sont les risques li\u00e9s \u00e0 l&#8217;utilisation de truffes ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>On pense souvent qu&#8217;il n&#8217;y a aucun risque associ\u00e9 \u00e0 l&#8217;utilisation de \u00ab produits naturels \u00bb comme les truffes. Cette id\u00e9e est fausse. Des \u00e9motions violentes et m\u00eame n\u00e9gatives peuvent r\u00e9sulter des effets de l&#8217;utilisation de truffes. La plupart des gens ont ce qu&#8217;on appelle \u00ab un bad trip \u00bb qui peut \u00eatre d\u00fb au fait que l&#8217;utilisateur ne peut pas g\u00e9rer les effets. Un peu comme les gens qui ne savent pas g\u00e9rer leur alcool. Un bad trip peut \u00eatre ennuyeux, mais presque jamais dangereux.     <\/p>\n<p>Les substances actives dans les truffes ne sont pas nocives pour le corps. Cependant, cela peut devenir dangereux dans des situations tr\u00e8s exceptionnelles. Par exemple, le risque d&#8217;avoir un bad trip est plus \u00e9lev\u00e9 si tu bois de l&#8217;alcool avant ou pendant le trip.  <\/p>\n<p><strong>Remarque :<\/strong> Assure-toi d&#8217;utiliser les truffes de mani\u00e8re responsable. Plus tu es prudent, moins il y a de risques. <\/p>\n<h3>Que se passe-t-il pendant un bad trip ?<\/h3>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Le trip s&#8217;av\u00e8re plus intense que tu ne le pensais \u00e0 l&#8217;avance<\/li>\n<li>Il y a g\u00e9n\u00e9ralement de la peur, de la panique, de l&#8217;agitation<\/li>\n<li>Ressentir des sentiments et des \u00e9motions d\u00e9sagr\u00e9ables<\/li>\n<li>Les maladies psychiatriques (d\u00e9pression, psychose) peuvent s&#8217;aggraver ou durer plus longtemps<\/li>\n<li>Blessure en faisant quelque chose de dangereux pendant un bad trip<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p><strong>Remarque :<\/strong> Lors d&#8217;un bad trip, assure-toi d&#8217;\u00eatre dans un endroit s\u00fbr pour ne pas risquer de te blesser accidentellement ou de blesser les autres. Par exemple : ne fais pas de v\u00e9lo et n&#8217;essaie pas de faire fonctionner une machine quelconque. <\/p>\n<p>Les personnes atteintes de maladies psychiatriques telles que la d\u00e9pression ou la psychose ne doivent pas prendre de truffes. Il y a un risque que la maladie r\u00e9apparaisse ou dure plus longtemps. <\/p>\n<p>Si tu es enceinte, si tu as une maladie et\/ou si tu prends des m\u00e9dicaments, il vaut mieux ne pas prendre de truffes. Les truffes sont potentiellement dangereuses pour ton enfant \u00e0 na\u00eetre. <\/p>\n<h3>Peut-on devenir d\u00e9pendant des truffes ?<\/h3>\n<p>Non, il n&#8217;est pas possible de devenir d\u00e9pendant des truffes. \u00c9tant donn\u00e9 les effets intenses qui r\u00e9sultent de l&#8217;utilisation de truffes, elles ne sont pas utilis\u00e9es tr\u00e8s souvent. Les truffes sont g\u00e9n\u00e9ralement utilis\u00e9es quelques fois au maximum. Le risque de d\u00e9pendance mentale n&#8217;est donc pas tr\u00e8s grand.   <\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9804 size-full\" src=\"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/truffles-in-Amsterdam.jpg\" alt=\"Truffes \u00e0 Amsterdam\" width=\"900\" height=\"506\" srcset=\"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/truffles-in-Amsterdam.jpg 900w, https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/truffles-in-Amsterdam-300x169.jpg 300w, https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/01\/truffles-in-Amsterdam-768x432.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"conseils-utiles-pour-lutilisation-de-truffes\"><\/span>Conseils utiles pour l&#8217;utilisation de truffes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Suis les conseils \u00e9num\u00e9r\u00e9s ci-dessous pour r\u00e9duire les risques. Les champignons et les truffes sont normalement s\u00fbrs si tu prends des pr\u00e9cautions de s\u00e9curit\u00e9 minimales mais n\u00e9cessaires. L&#8217;utilisation de drogues sans risque n&#8217;existe pas.  <\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Assure-toi qu&#8217;il y a quelqu&#8217;un autour qui est sobre au cas o\u00f9 quelqu&#8217;un serait submerg\u00e9 par les effets.<\/li>\n<li>Prends ton temps et assure-toi d&#8217;avoir un environnement s\u00fbr, calme et de confiance. Avec un dosage plus \u00e9lev\u00e9, c&#8217;est d\u00e9finitivement n\u00e9cessaire pour un \u00ab trip s\u00fbr \u00bb et agr\u00e9able. <\/li>\n<li>Ne prends des champignons ou des truffes que si tu te sens bien.<\/li>\n<li>Si tu deviens anxieux, reste calme : le sentiment d\u00e9sagr\u00e9able passe toujours.<\/li>\n<li>Ne r\u00e9siste pas \u00e0 ce qui te vient \u00e0 l&#8217;esprit ; d\u00e9tends-toi. Cela aide g\u00e9n\u00e9ralement de penser \u00e0 quelque chose d&#8217;amusant et d&#8217;\u00e9couter de la musique. <\/li>\n<li>Manger ou boire quelque chose peut t&#8217;aider \u00e0 te sentir mieux.<\/li>\n<li>\u00c9coute les signaux de ton corps et de ton esprit. Si tu trouves que tu ne peux pas le supporter, arr\u00eate. N&#8217;utilise plus de truffes !  <\/li>\n<li>Fumer de l&#8217;herbe prolonge et intensifie le trip. Il vaut mieux ne pas utiliser d&#8217;autres drogues lors de l&#8217;utilisation de truffes. <\/li>\n<li>N&#8217;ach\u00e8te pas de truffes aupr\u00e8s de vendeurs de rue. Ach\u00e8te tes truffes uniquement dans un bon smartshop. N&#8217;h\u00e9site pas \u00e0 demander conseil au commer\u00e7ant.  <\/li>\n<li>Ne combine pas champignons et truffes avec de l&#8217;alcool. Cela augmente le risque d&#8217;un bad trip. <\/li>\n<li>Ne participe pas \u00e0 la circulation apr\u00e8s avoir utilis\u00e9 des truffes !<\/li>\n<li>Prends ton temps ; n&#8217;utilise pas de truffes si tu n&#8217;as pas le temps. Assure-toi de n&#8217;avoir rien d&#8217;important \u00e0 faire le lendemain. Tu peux \u00eatre fatigu\u00e9 apr\u00e8s un trip aux truffes.  <\/li>\n<li>Ne prends pas de truffes si tu te sens anxieux, stress\u00e9 ou d\u00e9prim\u00e9. Les personnes atteintes de psychose latente ou de schizophr\u00e9nie ne doivent pas utiliser de truffes. <\/li>\n<li>Ne prends pas de truffes si tu prends des m\u00e9dicaments.<\/li>\n<li>Ne prends pas de truffes si tu es enceinte, si tu allaites ou si tu as moins de 18 ans.<\/li>\n<li>Conserve toujours tes truffes entre 4 et 6 degr\u00e9s Celsius. Elles peuvent \u00eatre conserv\u00e9es au r\u00e9frig\u00e9rateur jusqu&#8217;\u00e0 un mois. <\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<h3>Conclusion<\/h3>\n<p>La plupart des gens m\u00e2chent simplement les truffes puis les avalent, mais si tu n&#8217;aimes pas le go\u00fbt, tu peux toujours les m\u00e9langer avec du yaourt ou les mettre dans du th\u00e9 et attendre 20 minutes avant de boire l&#8217;infusion. Assure-toi que l&#8217;eau ne bout pas car cela peut d\u00e9truire d&#8217;importantes propri\u00e9t\u00e9s psych\u00e9d\u00e9liques des truffes magiques. <\/p>\n<p>Le dosage d\u00e9pend principalement de la puissance des truffes. Par cons\u00e9quent, assure-toi de bien t&#8217;informer lors de l&#8217;achat de truffes et assure-toi d&#8217;acheter des truffes qui correspondent \u00e0 ton exp\u00e9rience. Assure-toi de bien comprendre la force de la truffe souhait\u00e9e et mesure exactement combien tu dois en prendre. Pour \u00eatre du bon c\u00f4t\u00e9, prends toujours d&#8217;abord un petit dosage. Tu peux toujours augmenter le dosage, mais il n&#8217;y a pas de retour en arri\u00e8re possible.    <\/p>\n<p>Il est important de noter que les substances psych\u00e9d\u00e9liques ont des effets diff\u00e9rents sur chacun. Cela a \u00e0 voir avec les exp\u00e9riences individuelles, la psychologie et la physiologie. Si tu es d\u00e9butant, il est fortement recommand\u00e9 de prendre une petite dose dans un environnement o\u00f9 tu te sens \u00e0 l&#8217;aise. Si tu n&#8217;es pas dans un bon \u00e9tat mental, ne prends pas de truffes ! Prends d&#8217;abord soin de toi !    <\/p>\n<p><strong>Tu as des questions sur l&#8217;utilisation des truffes magiques ? Fais-le nous savoir dans les commentaires ! <\/strong>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][buttonsticky title=&#8221;Ach\u00e8te des truffes magiques en ligne sur microdosebros.com&#8221; link=&#8221;https:\/\/www.microdosebros.com\/product-category\/shroomshop\/best-shroomshop\/?ref=49&#8243; target=&#8221;true&#8221; nofollow=&#8221;true&#8221; el_id=&#8221;1731674534043-cb59c1e9-ec20&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Depuis l&#8217;interdiction des champignons magiques plus puissants en 2008, les truffes magiques sont\u2026<\/p>\n","protected":false},"author":1,"featured_media":6390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2026138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam<\/title>\n<meta name=\"description\" content=\"Les truffes sont tr\u00e8s populaires \u00e0 Amsterdam. Voici toutes les informations importantes sur l&#039;utilisation des truffes \u00e0 Amsterdam, o\u00f9 acheter des truffes \u00e0 Amsterdam, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam\" \/>\n<meta property=\"og:description\" content=\"Les truffes sont tr\u00e8s populaires \u00e0 Amsterdam. Voici toutes les informations importantes sur l&#039;utilisation des truffes \u00e0 Amsterdam, o\u00f9 acheter des truffes \u00e0 Amsterdam, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/\" \/>\n<meta property=\"og:site_name\" content=\"ThingstodoinAmsterdam.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thingstodoinamsterdamcom\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-06T17:50:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T14:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/04\/smartshop-truffels-amsterdam.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dani van Rooij\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dani van Rooij\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/\"},\"author\":{\"name\":\"Dani van Rooij\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#\\\/schema\\\/person\\\/b9338f79354c45c384df837d547041af\"},\"headline\":\"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam\",\"datePublished\":\"2025-03-06T17:50:30+00:00\",\"dateModified\":\"2026-04-28T14:29:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/\"},\"wordCount\":3786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/smartshop-truffels-amsterdam.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"fr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/\",\"url\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/\",\"name\":\"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/smartshop-truffels-amsterdam.jpg\",\"datePublished\":\"2025-03-06T17:50:30+00:00\",\"dateModified\":\"2026-04-28T14:29:13+00:00\",\"description\":\"Les truffes sont tr\u00e8s populaires \u00e0 Amsterdam. Voici toutes les informations importantes sur l'utilisation des truffes \u00e0 Amsterdam, o\u00f9 acheter des truffes \u00e0 Amsterdam, etc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#breadcrumb\"},\"inLanguage\":\"fr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/smartshop-truffels-amsterdam.jpg\",\"contentUrl\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/smartshop-truffels-amsterdam.jpg\",\"width\":900,\"height\":552,\"caption\":\"smartshop truffels amsterdam\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Things to do in Amsterdam\",\"item\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"blog\",\"item\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/\",\"name\":\"ThingstodoinAmsterdam.com\",\"description\":\"Amsterdam&#039;s highlights and hidden secrets\",\"publisher\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#organization\",\"name\":\"Things to do in Amsterdam\",\"alternateName\":\"Thingstodo B.V.\",\"url\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ThingsToDoInAmsterdam-Favicon-logo.png\",\"contentUrl\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ThingsToDoInAmsterdam-Favicon-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Things to do in Amsterdam\"},\"image\":{\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thingstodoinamsterdamcom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/#\\\/schema\\\/person\\\/b9338f79354c45c384df837d547041af\",\"name\":\"Dani van Rooij\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88186c27ad65b623125e1fe6136aa644fd9c64302f68210dbd1568349e64d66f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88186c27ad65b623125e1fe6136aa644fd9c64302f68210dbd1568349e64d66f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88186c27ad65b623125e1fe6136aa644fd9c64302f68210dbd1568349e64d66f?s=96&d=mm&r=g\",\"caption\":\"Dani van Rooij\"},\"description\":\"I grew up in Weesp, just outside Amsterdam, which has since become part of the city itself. My fascination with Amsterdam started by showing family and friends from abroad around the city and its surrounding areas, which eventually inspired me to co-found Things To Do In Amsterdam. As someone passionate about boating and watersports, Amsterdam\u2019s canals have always been one of my favourite parts of the city. My favourite Amsterdam event is SAIL, and I still think one of the best ways to experience Amsterdam is from the water on a canal cruise. When travelling, I enjoy going beyond the beaten path by renting a car or scooter and exploring destinations independently \u2014 an approach that also shapes the content I create about Amsterdam.\",\"url\":\"https:\\\/\\\/thingstodoinamsterdam.com\\\/fr\\\/author\\\/amsterdamfanatic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam","description":"Les truffes sont tr\u00e8s populaires \u00e0 Amsterdam. Voici toutes les informations importantes sur l'utilisation des truffes \u00e0 Amsterdam, o\u00f9 acheter des truffes \u00e0 Amsterdam, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/","og_locale":"fr_FR","og_type":"article","og_title":"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam","og_description":"Les truffes sont tr\u00e8s populaires \u00e0 Amsterdam. Voici toutes les informations importantes sur l'utilisation des truffes \u00e0 Amsterdam, o\u00f9 acheter des truffes \u00e0 Amsterdam, etc.","og_url":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/","og_site_name":"ThingstodoinAmsterdam.com","article_publisher":"https:\/\/www.facebook.com\/thingstodoinamsterdamcom","article_published_time":"2025-03-06T17:50:30+00:00","article_modified_time":"2026-04-28T14:29:13+00:00","og_image":[{"width":900,"height":552,"url":"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/04\/smartshop-truffels-amsterdam.jpg","type":"image\/jpeg"}],"author":"Dani van Rooij","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dani van Rooij","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#article","isPartOf":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/"},"author":{"name":"Dani van Rooij","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#\/schema\/person\/b9338f79354c45c384df837d547041af"},"headline":"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam","datePublished":"2025-03-06T17:50:30+00:00","dateModified":"2026-04-28T14:29:13+00:00","mainEntityOfPage":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/"},"wordCount":3786,"commentCount":0,"publisher":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#organization"},"image":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#primaryimage"},"thumbnailUrl":"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/04\/smartshop-truffels-amsterdam.jpg","articleSection":["blog"],"inLanguage":"fr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/","url":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/","name":"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam","isPartOf":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#primaryimage"},"image":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#primaryimage"},"thumbnailUrl":"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/04\/smartshop-truffels-amsterdam.jpg","datePublished":"2025-03-06T17:50:30+00:00","dateModified":"2026-04-28T14:29:13+00:00","description":"Les truffes sont tr\u00e8s populaires \u00e0 Amsterdam. Voici toutes les informations importantes sur l'utilisation des truffes \u00e0 Amsterdam, o\u00f9 acheter des truffes \u00e0 Amsterdam, etc.","breadcrumb":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#breadcrumb"},"inLanguage":"fr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/"]}]},{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#primaryimage","url":"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/04\/smartshop-truffels-amsterdam.jpg","contentUrl":"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2020\/04\/smartshop-truffels-amsterdam.jpg","width":900,"height":552,"caption":"smartshop truffels amsterdam"},{"@type":"BreadcrumbList","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/tout-ce-quil-faut-savoir-sur-lutilisation-des-truffes-a-amsterdam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Things to do in Amsterdam","item":"https:\/\/thingstodoinamsterdam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"blog","item":"https:\/\/thingstodoinamsterdam.com\/fr\/blog\/"},{"@type":"ListItem","position":3,"name":"Tout ce qu\u2019il faut savoir sur l\u2019utilisation des truffes \u00e0 Amsterdam"}]},{"@type":"WebSite","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#website","url":"https:\/\/thingstodoinamsterdam.com\/fr\/","name":"ThingstodoinAmsterdam.com","description":"Amsterdam&#039;s highlights and hidden secrets","publisher":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thingstodoinamsterdam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr"},{"@type":"Organization","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#organization","name":"Things to do in Amsterdam","alternateName":"Thingstodo B.V.","url":"https:\/\/thingstodoinamsterdam.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2025\/02\/ThingsToDoInAmsterdam-Favicon-logo.png","contentUrl":"https:\/\/thingstodoinamsterdam.com\/wp-content\/uploads\/2025\/02\/ThingsToDoInAmsterdam-Favicon-logo.png","width":512,"height":512,"caption":"Things to do in Amsterdam"},"image":{"@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thingstodoinamsterdamcom"]},{"@type":"Person","@id":"https:\/\/thingstodoinamsterdam.com\/fr\/#\/schema\/person\/b9338f79354c45c384df837d547041af","name":"Dani van Rooij","image":{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/secure.gravatar.com\/avatar\/88186c27ad65b623125e1fe6136aa644fd9c64302f68210dbd1568349e64d66f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88186c27ad65b623125e1fe6136aa644fd9c64302f68210dbd1568349e64d66f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88186c27ad65b623125e1fe6136aa644fd9c64302f68210dbd1568349e64d66f?s=96&d=mm&r=g","caption":"Dani van Rooij"},"description":"I grew up in Weesp, just outside Amsterdam, which has since become part of the city itself. My fascination with Amsterdam started by showing family and friends from abroad around the city and its surrounding areas, which eventually inspired me to co-found Things To Do In Amsterdam. As someone passionate about boating and watersports, Amsterdam\u2019s canals have always been one of my favourite parts of the city. My favourite Amsterdam event is SAIL, and I still think one of the best ways to experience Amsterdam is from the water on a canal cruise. When travelling, I enjoy going beyond the beaten path by renting a car or scooter and exploring destinations independently \u2014 an approach that also shapes the content I create about Amsterdam.","url":"https:\/\/thingstodoinamsterdam.com\/fr\/author\/amsterdamfanatic\/"}]}},"_links":{"self":[{"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/posts\/2026138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/comments?post=2026138"}],"version-history":[{"count":9,"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/posts\/2026138\/revisions"}],"predecessor-version":[{"id":2542362,"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/posts\/2026138\/revisions\/2542362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/media\/6390"}],"wp:attachment":[{"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/media?parent=2026138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/categories?post=2026138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thingstodoinamsterdam.com\/fr\/wp-json\/wp\/v2\/tags?post=2026138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}